
     {"id":68947,"date":"2021-09-14T06:48:42","date_gmt":"2021-09-14T04:48:42","guid":{"rendered":"https:\/\/elisvillamartin.com\/?page_id=68947"},"modified":"2026-04-23T17:07:36","modified_gmt":"2026-04-23T15:07:36","slug":"cuotas","status":"publish","type":"page","link":"https:\/\/elisvillamartin.com\/es\/cuotas\/","title":{"rendered":"Cuotas Escolares"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<section  class=\"bg-video-wrap hero section hero--centertext   \" style='background: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-282.jpg) center ;background-size:cover ;'>\n                <div class=\"bg-overlay\" style='background:#0a0a0a;opacity:0.4;'><\/div>\n                <div class=\"overlay\" >\n                  <div class=\"container-fluid\">\n                    <div class=\"row\">\n                      <div class=\"col-md-12 col-lg-12\">\n\n                        <div class=\"caption text-start\"><div class=\"component sub-heading\" >\n                              <h1 class=\"display-h1\">Cuotas Escolares<\/h1>\n                            <\/div><\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/section><div class='row  m-x-0 breadcrumb-wrap ' style=''><div class='container-fluid' >\n                <nav aria-label='breadcrumb'><ol class=\"breadcrumb mt-3\">\n                  <li class=\"breadcrumb-item\"><a href=\"https:\/\/elisvillamartin.com\/es\/\">Home<\/a><\/li>\n                  <li class=\"breadcrumb-item active\" aria-current=\"page\">Cuotas Escolares<\/li>\n                <\/ol>\n              <\/nav>\n              <\/div>\n            <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]\n    <section  style='background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/white-background.png);' class=\"section       section--withBG \" ><div class=\"bg-overlay\" ><\/div><div class=\"container-fluid\"><div class=\"row  justify-content-between  \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Lo mejor para el futuro de tus hijos<\/h2><\/div>\n                        <div class=\"sub-heading component \">\n                        <p class=\"body-medium\">Ser miembro de ELIS Villamart\u00edn significa ser parte de una comunidad educativa solidaria que fomenta el pensamiento creativo y curioso dentro de una cultura de apoyo y est\u00edmulo constantes.<br \/>\n<br \/>\nAvalados por profesores e instalaciones excepcionales, nuestro curr\u00edculo enriquecido y una tecnolog\u00eda educativa l\u00edder, ayudaremos a tu hijo a alcanzar todo su potencial y prepararlo para las demandas de un mundo en constante cambio.<br \/>\n<br \/>\nTenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta. <\/p>\n                        <\/div><\/div><div class=\"component link\"><a href=\"\/es\/proceso-de-admision\/\" class=\" btn btn-primary\">Proceso de Admisi\u00f3n<\/a><\/div><\/div>\n                    <div class=\"col-lg-5 col-md-6    \"><div class=\"component IconWithText-list\">\n                    <div class=\"card\"><div class=\"card-header section--blue\" style='background-color:#3c5128;px'>\n                            <div class=\"sub-heading component mb-0\">\n                                <p class=\"body-medium\">Ver m\u00e1s:<\/p>\n                            <\/div>\n                        <\/div><div class=\"card-body section--white\">\n                            <div class=\"component list list--IconWithText-list bordered--icon blue-icon\">\n                                <ul><li><div class=\"component link\"><a href=\"#early-years-foundation-fees\" class=\" btn btn-link\">Cuotas de Infantil<\/a><\/div><\/li><li><div class=\"component link\"><a href=\"#primary-education-fees\" class=\" btn btn-link\">Cuotas de Primaria<\/a><\/div><\/li><li><div class=\"component link\"><a href=\"#secondary-education-fees\" class=\" btn btn-link\">Cuotas de Secundaria<\/a><\/div><\/li><li><div class=\"component link\"><a href=\"#sixth-form-fees\" class=\" btn btn-link\">Cuotas de Bachillerato<\/a><\/div><\/li><li><div class=\"component link\"><a href=\"#additional-fees\" class=\" btn btn-link\">Cuotas adicionales<\/a><\/div><\/li>              <\/ul>\n                            <\/div>\n                    <\/div>  <\/div>\n            <\/div> <\/div>\n             <\/div>\n        <\/div>\n<\/section>[\/vc_column][\/vc_row][vc_row][vc_column]\n    <section  style='background-color:#f3f4f2;' class=\"section  light-color section--white  pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas de 2026 - 2027<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section>\n    <section  id=\"early-years-foundation-fees\"  style='background-color:#f3f4f2;' class=\"section  light-color section--white  pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas de Infantil<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section><section  style='background-color:#f3f4f2;' class=\"section   section--blue  \"><!-- Large content area -->\n            \t<div class=\"container-fluid \">\n                    <div class=\"row m-x-0\"><div class=\"component fee-table \" >\n                                    <table class=\"table table-with-multi-cell\">\n                                        <thead class=\"table-light\">\n                                            <tr><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>EDAD<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>INGLATERRA<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>ESPA\u00d1A<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>CUOTA MENSUAL (10 meses\/a\u00f1o)<\/b><\/h6><\/th><\/tr><\/thead><tbody><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">3-4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Nursery \u2013 Media jornada<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Infantil 3<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">562,5\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">3-4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Nursery<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Infantil 3<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">750\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">4-5<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Reception<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Infantil 4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">750\u20ac<\/td><\/tr><\/tbody><\/table><\/div><div class=\"component mt-2\"><\/div><\/div>\n                <\/div><\/section>\n            <div class=\"wrapper\">\n    <section  id=\"primary-education-fees\"  style='' class=\"section    container-width pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas de Primaria<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section>\n            <\/div>\n        <div class=\"wrapper\"><section  style='' class=\"section  container-width   \"><!-- Large content area -->\n            \t<div class=\"container-fluid \">\n                    <div class=\"row m-x-0\"><div class=\"component fee-table \" >\n                                    <table class=\"table table-with-multi-cell\">\n                                        <thead class=\"table-light\">\n                                            <tr><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>EDAD<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>INGLATERRA<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>ESPA\u00d1A<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>CUOTA MENSUAL (10 meses\/a\u00f1o)<\/b><\/h6><\/th><\/tr><\/thead><tbody><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">5-6<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 1<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Infantil 5<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">805\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">6-7<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 2<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 1<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">805\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">7-8<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 3<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 2<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">880\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">8-9<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 3<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">880\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">9-10<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 5<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">880\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">10-11<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 6<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 5<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">880\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">11-12<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 7<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Primaria 6<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">880\u20ac<\/td><\/tr><\/tbody><\/table><\/div><div class=\"component mt-2\"><\/div><\/div>\n                <\/div><\/section>\n        <\/div>\n    <section  id=\"secondary-education-fees\"  style='background-color:#f3f4f2;' class=\"section  light-color section--white  pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas de Secundaria<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section><section  style='background-color:#f3f4f2;' class=\"section   section--blue  \"><!-- Large content area -->\n            \t<div class=\"container-fluid \">\n                    <div class=\"row m-x-0\"><div class=\"component fee-table \" >\n                                    <table class=\"table table-with-multi-cell\">\n                                        <thead class=\"table-light\">\n                                            <tr><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>EDAD<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>INGLATERRA<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>ESPA\u00d1A<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>CUOTA MENSUAL (10 meses\/a\u00f1o)<\/b><\/h6><\/th><\/tr><\/thead><tbody><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">12-13<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 8<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Secundaria 1<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">985\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">13-14<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 9<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Secundaria 2<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">985\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">14-15<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 10<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Secundaria 3<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">985\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">15-16<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 11<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Secundaria 4<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">985\u20ac<\/td><\/tr><\/tbody><\/table><\/div><div class=\"component mt-2\"><\/div><\/div>\n                <\/div><\/section>\n            <div class=\"wrapper\">\n    <section  id=\"sixth-form-fees\"  style='' class=\"section    container-width pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas de Bachillerato<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section>\n            <\/div>\n        <div class=\"wrapper\"><section  style='' class=\"section  container-width   \"><!-- Large content area -->\n            \t<div class=\"container-fluid \">\n                    <div class=\"row m-x-0\"><div class=\"component fee-table \" >\n                                    <table class=\"table table-with-multi-cell\">\n                                        <thead class=\"table-light\">\n                                            <tr><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>EDAD<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>INGLATERRA<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>ESPA\u00d1A<\/b><\/h6><\/th><th  style=\"background-color:#3c5128;\"><h6 class=\"\" style=\"font-size:14px;text-align:left;\"><b>CUOTA MENSUAL (10 meses\/a\u00f1o)<\/b><\/h6><\/th><\/tr><\/thead><tbody><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">16-17<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 12<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Bachillerato 1<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">999\u20ac<\/td><\/tr><tr ><td align=\"left\" class=\"\" style=\"font-size:14px;\">17-18<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Year 13<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">Bachillerato 2<\/td><td align=\"left\" class=\"\" style=\"font-size:14px;\">999\u20ac<\/td><\/tr><\/tbody><\/table><\/div><div class=\"component mt-2\"><\/div><\/div>\n                <\/div><\/section>\n        <\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;gradient3 white-section&#8221;][vc_column]\n    <section  id=\"sixth-form-fees\"  style='' class=\"section     pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Cuotas adicionales<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section><section  id=\"additional-fees\"  class=\"section      \" style=''><div class=\"container-fluid\">\n\t\t\t\t\t<div class=\"row m-0 align-items-center\">\n\t\t\t\t\t\t<div class=\"col-sm-12 col-md-12 col-lg-12 mx-auto\"><ul class=\"nav nav-tabs d-none d-md-flex\" id=\"myTab\" role=\"tablist\"><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link active\" id=\"Feature-1\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature1\" type=\"button\" role=\"tab\" aria-controls=\"Feature1\" aria-selected=\"true\">Cuota de inscripci\u00f3n<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-2\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature2\" type=\"button\" role=\"tab\" aria-controls=\"Feature2\" aria-selected=\"true\">Comedor<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-3\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature3\" type=\"button\" role=\"tab\" aria-controls=\"Feature3\" aria-selected=\"true\">Transporte<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-4\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature4\" type=\"button\" role=\"tab\" aria-controls=\"Feature4\" aria-selected=\"true\">Tarifas de ex\u00e1menes<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-5\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature5\" type=\"button\" role=\"tab\" aria-controls=\"Feature5\" aria-selected=\"true\">Libros de texto<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-6\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature6\" type=\"button\" role=\"tab\" aria-controls=\"Feature6\" aria-selected=\"true\">Uniformes escolares<\/button>\n\t\t\t<\/li><li class=\"nav-item\" role=\"presentation\">\n\t\t\t\t<button class=\"nav-link\" id=\"Feature-7\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature7\" type=\"button\" role=\"tab\" aria-controls=\"Feature7\" aria-selected=\"true\">Descuentos sobre cuotas<\/button>\n\t\t\t<\/li><\/ul><div class=\"tab-content\" id=\"myTabContent\"><div class=\"tab-pane fade show active\" id=\"Feature1\" role=\"tabpanel\" aria-labelledby=\"Feature1-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link active\" id=\"Feature-1\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature1\" type=\"button\" role=\"tab\" aria-controls=\"Feature1\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">La cuota de inscripci\u00f3n para nuevos estudiantes en nuestro colegio internacional en Villamart\u00edn consta de un \u00fanico pago de 1.500 euros. Este importe no es reembolsable.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-203.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature2\" role=\"tabpanel\" aria-labelledby=\"Feature2-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-2\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature2\" type=\"button\" role=\"tab\" aria-controls=\"Feature2\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">El coste de la cuota de comedor es de 1.800\u20ac por a\u00f1o (180\u20ac por mes). La cuota de comedor es obligatoria para todos los estudiantes hasta Year 11 inclusive. <\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-209.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature3\" role=\"tabpanel\" aria-labelledby=\"Feature3-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-3\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature3\" type=\"button\" role=\"tab\" aria-controls=\"Feature3\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">Las tarifas de transporte dependen de la ruta y oscilan entre 150\u20ac y 190\u20ac por mes.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-045.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature4\" role=\"tabpanel\" aria-labelledby=\"Feature4-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-4\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature4\" type=\"button\" role=\"tab\" aria-controls=\"Feature4\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">Hay costos adicionales para ex\u00e1menes internacionales como idiomas (ESOL, alem\u00e1n y franc\u00e9s), IGCSE (A\u00f1o 11), AS y A-Level (A\u00f1os 11 a 13). Algunos cursos opcionales de IGCSE y A-Level requieren que los estudiantes realicen viajes de estudio e investigaci\u00f3n con un costo adicional.<br><br>Puedes elegir la opci\u00f3n de Pago Anticipado de Tarifas de Examen, pagando una tarifa de octubre a marzo, que se acumular\u00e1 para las tarifas de ex\u00e1menes posteriores de A-Level e IGCSE.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-290.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature5\" role=\"tabpanel\" aria-labelledby=\"Feature5-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-5\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature5\" type=\"button\" role=\"tab\" aria-controls=\"Feature5\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">Las listas de libros de texto se publican durante el tercer trimestre. Todos los textos, ya sean suscripciones digitales o libros de texto f\u00edsicos, se reservan en Secretar\u00eda. Las suscripciones digitales se facturan directamente desde el colegio.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-182.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature6\" role=\"tabpanel\" aria-labelledby=\"Feature6-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-6\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature6\" type=\"button\" role=\"tab\" aria-controls=\"Feature6\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">El uniforme escolar es obligatorio hasta el final de Year 11. No se adquiere en el colegio, sino en El Corte Ingl\u00e9s.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-015.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"tab-pane fade\" id=\"Feature7\" role=\"tabpanel\" aria-labelledby=\"Feature7-tab\">\n\t\t\t\t\t\t<div class=\"d-block d-md-none\">\n\t\t\t\t\t\t\t<button class=\"nav-link\" id=\"Feature-7\" data-bs-toggle=\"tab\" data-bs-target=\"#Feature7\" type=\"button\" role=\"tab\" aria-controls=\"Feature7\" aria-selected=\"true\"><\/button>\n\n\t\t\t\t\t\t<\/div><div class=\"row m-0\"><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t<h6><\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sub-heading component\">\n\t\t\t\t\t\t\t\t\t<p class=\"p\"><p class=\"body-medium\">La estructura de los descuentos (aplicables solamente a la escolaridad) y en funci\u00f3n del n\u00famero de hijos matriculados en el colegio es del 10% para el segundo hijo, 20% para el tercer hijo y 40% a partir del cuarto hijo.<br><br>Si realiza el pago de la totalidad anual del comedor y la escolaridad, en el mes de septiembre o con anterioridad a este mes, se aplicar\u00e1 un 2% de descuento, por pronto pago (aplicable \u00fanicamente a la escolaridad). No se aplican descuentos por hermanos en la modalidad de Nursery a media jornada.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class=\"col-lg-6 col-md-6\">\n\t\t\t\t\t\t\t\t<div class=\"component h-100\"><div class=\"callout-img halfcol--img\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-022.jpg);\">\n\t\t\t\t\t\t\t<\/div><figcaption><\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div><\/div>\n\t\t\t\t\t<\/div><\/div><\/section>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694702386168{margin-top: 5px !important;background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/book-a-visit-banner-v3.png?id=69324) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;gradient2&#8243;][vc_column]<section  style='' class=\"section   section--blue   \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\"><div class=\"h2 \">Ven a un Open Day<\/div>\n<p>&nbsp;<\/p>\n<p>Descubre lo que una educaci\u00f3n en ELIS Villamart\u00edn tiene que ofrecer<\/p>\n<\/div><div class=\"component link\"><a href=\"\/es\/reservar-una-jornada-de-puertas-abiertas\/\" class=\" btn btn-primary\">Reserve ahora<\/a><\/div><div class=\"flex-button\"><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"wrapper \" ><section  id=\"your-childs-journey\"  class=\"section container-width   section--blue \" style='background-color:#3c5128;margin-top:80px;'>\n    <div class=\"container-fluid \">\n        <div class=\"row m-0 centerText\">\n            \n<div class=\"col-sm-12 col-md-12 col-lg-10 col-xl-8 mx-auto\">       <div class=\"component\">\n                    <h3 class=\"h5\">Inicia una experiencia de aprendizaje \u00fanica\n                    <\/h3>\n                <\/div>     <\/div><div class=\"col-sm-12 col-md-7 col-lg-6 col-xl-5 mx-auto\">       <div class=\"component mt-3\">\n                    <div class=\"body-large\"><\/p>\n<p style=\"text-align: center\">Descubre el enriquecedor viaje educativo que espera a tu hijo en las diferentes etapas de El Limonar International School Villamart\u00edn.<\/p>\n<p><\/div>\n                <\/div>        <div class=\"component link\"><div class=\"component link\"><a href=\"\/es\/viaje-educativo-del-alumno\/\" class=\" btn btn-primary\">El viaje de tu hijo<\/a><\/div><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><section class=\"section cards--section pt-0 container-width  section--blue \" style='background-color:#3c5128;margin-bottom:80px;'>\n                <div class=\"container-fluid \">\n                    <div class=\"row m-0\"><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_2030\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-001.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal9495\">\n                                           <a href=\"\" class=\"body-large-bold\">Infantil<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">3 - 5 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal9495\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_7920\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-270.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal4078\">\n                                           <a href=\"\" class=\"body-large-bold\">Primaria<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">5 - 11 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal4078\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_7240\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-179.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal3222\">\n                                           <a href=\"\" class=\"body-large-bold\">Secundaria<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">11 - 16 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal3222\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_6409\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-169.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal2350\">\n                                           <a href=\"\" class=\"body-large-bold\">Bachillerato<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">16 - 18 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal2350\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>          <\/div>\n                <\/div>\n            <\/section><\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal9495\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/infantil\/\" class=\"highlights__link btn btn-link\">Infantil<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">3 - 5 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Descubre nuestro curr\u00edculo dise\u00f1ado para ni\u00f1os de 3 a 5 a\u00f1os, que ofrece la base ideal para su itinerario educativo. <\/li>                       <li>Nuestras instalaciones proporcionan un ambiente acogedor, con personal altamente cualificado que garantiza una transici\u00f3n fluida desde la guarder\u00eda al colegio y un aprendizaje integral en siete \u00e1reas esenciales. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/infantil\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite8948 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-001.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal4078\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/primaria\/\" class=\"highlights__link btn btn-link\">Primaria<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">5 - 11 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Una educaci\u00f3n hol\u00edstica que prepara a los ni\u00f1os de 5 a 11 a\u00f1os para un crecimiento y aprendizaje continuos a lo largo de su vida. <\/li>                       <li>Nuestro curr\u00edculo combina lo mejor de la educaci\u00f3n brit\u00e1nica y espa\u00f1ola, ofreciendo un tercer idioma y un programa de tutor\u00eda individualizada. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/primaria\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite3906 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-270.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal3222\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/secundaria\/\" class=\"highlights__link btn btn-link\">Secundaria<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">11 - 16 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Nuestro curr\u00edculo de Secundaria prepara a los estudiantes para ex\u00e1menes internacionales externos y rigurosos mejorando sus habilidades en diferentes materias. <\/li>                       <li>Nuestro compromiso con la excelencia se ve reflejado en nuestras instalaciones de primer nivel, que mejoran el aprendizaje y potencian la preparaci\u00f3n de los alumnos para el futuro. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/secundaria\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite4677 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-179.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal2350\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/bachillerato\/\" class=\"highlights__link btn btn-link\">Bachillerato<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">16 - 18 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>ELIS Villamart\u00edn prepara a los estudiantes para acceder a universidades del Reino Unido, Espa\u00f1a o internacionales mediante un programa \u00fanico de orientaci\u00f3n vocacional. <\/li>                       <li>Nuestro Bachillerato combina A-Levels Internacionales y Bachillerato espa\u00f1ol, junto con un apoyo personalizado que incluye tutor\u00edas, intercambios, viajes y programas de preparaci\u00f3n para la universidad. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/bachillerato\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite7713 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-169.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<section  style='background-color:#f3f4f2;' class=\"section  light-color section--white pb-0  \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\">\n                                        <h2 class=\"h5\">Te puede interesar<\/h2>\n                                    <\/div><div class=\"sub-heading component\"><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section><section  class=\"section    pt-0  section--blue\" style='background-color:#f3f4f2;'><div class=\"container-fluid section--blue\" style='background-color:#f3f4f2'><style>\n            .background-box .heading .h5:after {\n                display:none;\n            }\n            <\/style><div class=\"row m-0 justify-content-center pt-3 pt-md-3\"><style>\n                .thumbnail_img_overlay_3746 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_3746 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_3746 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_3746 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_3746 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_3746 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_3746 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_3746\">   <a class=\"\" href = \"\/es\/excelencia-academica\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-182.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Excelencia Acad\u00e9mica<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_1291 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_1291 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_1291 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_1291 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_1291 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_1291 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_1291 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_1291\">   <a class=\"\" href = \"\/es\/instalaciones-y-localizacion\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-299.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Instalaciones y Localizaci\u00f3n<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_9861 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_9861 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_9861 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_9861 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_9861 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_9861 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_9861 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_9861\">   <a class=\"\" href = \"\/es\/proceso-de-admision\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-165.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Proceso de Admisi\u00f3n<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_1473 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_1473 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_1473 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_1473 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_1473 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_1473 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_1473 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_1473\">   <a class=\"\" href = \"\/es\/puertas-abiertas-y-visitas\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-047.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Puertas Abiertas y Visitas<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><\/div><\/div>\n            <\/section>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694166801591{background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/prospectus-leaf.png?id=69327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]<section  style='' class=\"section   section--white   \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\">\n                                        <h2 class=\"h5\">Descubre m\u00e1s sobre ELIS Villamart\u00edn<\/h2>\n                                    <\/div><div class=\"sub-heading component\"><\/div><div class=\"component link\"><a href=\"\/es\/descarga-nuestro-catalogo\/\" class=\" btn btn-primary\">Solicita nuestro Cat\u00e1logo<\/a><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section>[\/vc_column][\/vc_row][vc_row][vc_column]<section class=\"section section--blue bottom-step TopBottomBorder   \" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-301.jpg');;background-position-y:75%;;\"><style>.bottom-step.section--blue:before {background: rgba(106,157,65,0.8);}<\/style><div class=\"container-fluid\"><div class=\"row\"><div class=\"col-sm-12\"><div class=\"component title\"><p class=\"body-small\">Ponte en Contacto<\/p><\/div><\/div><\/div><div class=\"row\"><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/haz-una-consulta\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Haz una Consulta<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/solicita-una-visita-privada\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Solicita una visita privada<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/reservar-una-jornada-de-puertas-abiertas\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Ven a un D\u00eda de Puertas Abiertas<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/section>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row el_class=&#8221;gradient3 white-section&#8221;][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694702386168{margin-top: 5px !important;background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/book-a-visit-banner-v3.png?id=69324) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;gradient2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694166801591{background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/prospectus-leaf.png?id=69327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":390,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-68947","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuotas Escolares - ELIS Villamart\u00edn<\/title>\n<meta name=\"description\" content=\"Tenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elisvillamartin.com\/es\/cuotas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuotas Escolares - ELIS Villamart\u00edn\" \/>\n<meta property=\"og:description\" content=\"Tenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elisvillamartin.com\/es\/cuotas\/\" \/>\n<meta property=\"og:site_name\" content=\"El Limonar International School Villamart\u00edn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T15:07:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuotas Escolares - ELIS Villamart\u00edn","description":"Tenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elisvillamartin.com\/es\/cuotas\/","og_locale":"es_ES","og_type":"article","og_title":"Cuotas Escolares - ELIS Villamart\u00edn","og_description":"Tenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta.","og_url":"https:\/\/elisvillamartin.com\/es\/cuotas\/","og_site_name":"El Limonar International School Villamart\u00edn","article_publisher":"https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/","article_modified_time":"2026-04-23T15:07:36+00:00","og_image":[{"width":1240,"height":575,"url":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elisvillamartin.com\/es\/cuotas\/","url":"https:\/\/elisvillamartin.com\/es\/cuotas\/","name":"Cuotas Escolares - ELIS Villamart\u00edn","isPartOf":{"@id":"https:\/\/elisvillamartin.com\/es\/#website"},"datePublished":"2021-09-14T04:48:42+00:00","dateModified":"2026-04-23T15:07:36+00:00","description":"Tenemos cuotas escolares y adicionales transparentes que se pueden ver a continuaci\u00f3n. Por favor, cont\u00e1ctanos si tienes alguna pregunta.","breadcrumb":{"@id":"https:\/\/elisvillamartin.com\/es\/cuotas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elisvillamartin.com\/es\/cuotas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elisvillamartin.com\/es\/cuotas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elisvillamartin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cuotas Escolares"}]},{"@type":"WebSite","@id":"https:\/\/elisvillamartin.com\/es\/#website","url":"https:\/\/elisvillamartin.com\/es\/","name":"El Limonar International School Villamart\u00edn","description":"ELIS Villamart\u00edn is part of the Cognita Schools Group","publisher":{"@id":"https:\/\/elisvillamartin.com\/es\/#organization"},"alternateName":"ELIS Villamartin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elisvillamartin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elisvillamartin.com\/es\/#organization","name":"ELIS Villamart\u00edn","alternateName":"ELIS Villamart\u00edn","url":"https:\/\/elisvillamartin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elisvillamartin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","contentUrl":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","width":1240,"height":575,"caption":"ELIS Villamart\u00edn"},"image":{"@id":"https:\/\/elisvillamartin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/","https:\/\/www.instagram.com\/elis.villamartin"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/users\/390"}],"replies":[{"embeddable":true,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/comments?post=68947"}],"version-history":[{"count":34,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68947\/revisions"}],"predecessor-version":[{"id":74082,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68947\/revisions\/74082"}],"wp:attachment":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/media?parent=68947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}