
     {"id":68977,"date":"2021-09-22T11:41:27","date_gmt":"2021-09-22T09:41:27","guid":{"rendered":"https:\/\/elisvillamartin.com\/?page_id=68977"},"modified":"2025-12-12T14:35:49","modified_gmt":"2025-12-12T13:35:49","slug":"secundaria","status":"publish","type":"page","link":"https:\/\/elisvillamartin.com\/es\/secundaria\/","title":{"rendered":"Secundaria"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<section  class=\"bg-video-wrap hero section hero--centertext   \" style='background: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-179.jpg) center ;background-size:cover ;'>\n                <div class=\"bg-overlay\" style='background:#000000;opacity:0.4;'><\/div>\n                <div class=\"overlay\" >\n                  <div class=\"container-fluid\">\n                    <div class=\"row\">\n                      <div class=\"col-md-12 col-lg-12\">\n\n                        <div class=\"caption text-start\"><div class=\"component sub-heading\" >\n                              <h1 class=\"display-h1\">Secundaria<\/h1>\n                            <\/div><\/div>\n                      <\/div>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/section><div class='row  m-x-0 breadcrumb-wrap ' style=''><div class='container-fluid' >\n                <nav aria-label='breadcrumb'><ol class=\"breadcrumb mt-3\">\n                  <li class=\"breadcrumb-item\"><a href=\"https:\/\/elisvillamartin.com\/es\/\">Home<\/a><\/li>\n                  <li class=\"breadcrumb-item active\" aria-current=\"page\">Secundaria<\/li>\n                <\/ol>\n              <\/nav>\n              <\/div>\n            <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]\n    <section  style='background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/white-background.png);' class=\"section      no-padding-list section--withBG \" ><div class=\"bg-overlay\" ><\/div><div class=\"container-fluid\"><div class=\"row  justify-content-between  \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Del conocimiento al \u00e9xito: trazando el camino hacia la ense\u00f1anza superior<\/h2><\/div>\n                        <div class=\"sub-heading component \">\n                        <p class=\"body-medium\">El Limonar International School Villamart\u00edn sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas impartidas en ingl\u00e9s. Hasta el final de Secundaria, en Year 11, los alumnos estudian el 80% de la jornada en ingl\u00e9s y el 20% restante en espa\u00f1ol. En Year 7, 8 y 9, tambi\u00e9n es obligatorio estudiar una tercera lengua (franc\u00e9s o alem\u00e1n).<br \/>\n<br \/>\nDurante Year 10 y Year 11, todos los alumnos estudian para obtener los IGCSE y siguen el programa obligatorio en espa\u00f1ol establecido por el Ministerio de Educaci\u00f3n espa\u00f1ol. <\/p>\n                        <\/div><\/div><\/div>\n                    <div class=\"col-lg-5 col-md-6    \"> <div class=\"component\"><div class=\"card border-0 section--blue\" style='background-color:#3c5128'>\n                                         <div class=\"card-body\" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><div  class=\"h5 h5 \">Experimenta el camino hacia un futuro de \u00e9xito<\/div><\/div>\n                        <div class=\"sub-heading component \">\n                        <p class=\"body-medium\"><\/br>Experimenta el camino hacia un futuro pr\u00f3spero.<\/p>\n                        <\/div><\/div><div class=\"component link\"><a href=\"\/es\/reservar-una-jornada-de-puertas-abiertas\/\" class=\" btn btn-primary btn-primary--border\">Ven a un D\u00eda de Puertas Abiertas<\/a><\/div>   <\/div>\n                                    <\/div>\n                                <\/div> <\/div>\n             <\/div>\n        <\/div>\n<\/section>[\/vc_column][\/vc_row][vc_row][vc_column]<section  class=\"section callout-img full--img  has-bg-image   \" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-184.jpg'); background-size: cover;\"><div class=\"img-overlay overlay2498\"><\/div><div class=\"container-fluid\">\n                                <div class=\"row \"><style>\n                @media (max-width: 767px) {\n                    .img_overlay_uniq5137 {\n                        width: 90%;\n                    }\n                }\n                <\/style><div class=\"col-lg-12 col-md-12\">\n                                    <div class=\"heading component\">\n                                    <div class=\"\" >\n                                    <div class=\"img-overlay-middle img_overlay_uniq5137\" style=\" \">\n                                    <div><style>\n                                            .callout-img blockquote::before {\n                                                content: open-quote;\n                                            }\n                                            .callout-img blockquote::after {\n                                                content: close-quote;\n                                            }\n                                            <\/style><div class=\"heading component\">\n                                                    <blockquote class=\"h4\">Como padres, apreciamos la educaci\u00f3n integral y la dedicaci\u00f3n al aprendizaje de idiomas que se brinda en ELIS. Nuestro hijo recibe una base acad\u00e9mica muy completa para tener \u00e9xito en el futuro.<\/blockquote>\n                                                <\/div><div class=\"heading component\">\n                                                                        <p class=\"body-large\">&#8211; Padres de un estudiante de Secundaria<\/p>\n                                                                    <\/div><div class=\"component link cust-link\"><\/div><\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        \n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/section>[\/vc_column][\/vc_row][vc_row][vc_column]\n    <section  id=\"english-immersion-programme\"  style='' class=\"section        \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6    order-2 order-md-1   \" ><div class=\"component link\"><div class=\"ratio ratio-16x9 callout-img halfcol--img image_overlay_6212\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-192.jpg);\"><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6  order-1 order-md-2   \"><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Programas de Inmersi\u00f3n en Ingl\u00e9s<\/h2><\/div>\n                        <div class=\"sub-heading component \">\n                        <p class=\"body-medium\">Los alumnos con poco o ning\u00fan conocimiento de ingl\u00e9s pueden ser admitidos en el colegio para unirse a nuestros Programas de Inmersi\u00f3n en Ingl\u00e9s, que duran desde un trimestre a un a\u00f1o acad\u00e9mico completo.<br \/>\n<br \/>\nLos alumnos centran sus esfuerzos en aprender ingl\u00e9s para elevar su competencia ling\u00fc\u00edstica a un nivel que les permita funcionar en la clase com\u00fan. <\/p>\n                        <\/div><\/div> <\/div>\n             <\/div>\n        <\/div>\n<\/section>[\/vc_column][\/vc_row][vc_row el_class=&#8221;gradient1&#8243;][vc_column]<section  style='' class=\"section    pb-0  white-section\"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\">\n                                        <h2 class=\"h5\">\u00a1Donde el talento crece todo el a\u00f1o!<\/h2>\n                                    <\/div><div class=\"sub-heading component\"><\/div><div class=\"flex-button\"><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section><section  class=\"section pt-0  button-align-left   \" style=''><div class=\"container-fluid \" style=''><div class=\"row m-0 align-items-center\"><\/div>\n    <\/div>\n\n    <div class=\"container-fluid pt-0 \" style=''>\n        <div class=\"row m-0\">   <div class=\"col-lg-4 col-md-4 col-sm-4 mb-3 mb-lg-0 pb-4\">\n                <div class=\"card card--white center-button-flexible\">\n                    <div class=\"thumbitem_overlay_7979\"><img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-081.jpg\" class=\"card-img-top \" alt=\"img\"><\/div>\n                    <div class=\"card-body thumbitemDesc \">\n                      <div><div class=\"card-title body-medium\"><h7>Actividades Extraescolares<\/h7>\n<p>Las actividades extraescolares son muy importantes, no s\u00f3lo por ser divertidas, sino porque proporcionan un contexto en el que los estudiantes pueden desarrollar cualidades y atributos que resultan \u00fatiles tanto en el colegio como m\u00e1s adelante en la vida.<\/p><\/div><\/div><div class=\"component link text-center  btnBottom-flexible\"><a href=\"\/es\/actividades-extraescolares\/\" class=\" btn btn-primary btn-primary--border\">Actividades Extraescolares<\/a><\/div><\/div>\n                <\/div>\n            <\/div>   <div class=\"col-lg-4 col-md-4 col-sm-4 mb-3 mb-lg-0 pb-4\">\n                <div class=\"card card--white center-button-flexible\">\n                    <div class=\"thumbitem_overlay_6740\"><img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-229.jpg\" class=\"card-img-top \" alt=\"img\"><\/div>\n                    <div class=\"card-body thumbitemDesc \">\n                      <div><div class=\"card-title body-medium\"><h7>Escuela de Musica<\/h7>\n<p>En ELIS Villamart\u00edn creemos que la educaci\u00f3n musical es parte esencial de una educaci\u00f3n integral. Nuestra Escuela de M\u00fasica ofrece ense\u00f1anza personalizada y la oportunidad de unirse a grupos musicales, todo dentro de la comodidad de nuestro campus.<\/p><\/div><\/div><div class=\"component link text-center  btnBottom-flexible\"><a href=\"\/es\/escuela-de-musica\/\" class=\" btn btn-primary btn-primary--border\">Escuela de M\u00fasica<\/a><\/div><\/div>\n                <\/div>\n            <\/div>   <div class=\"col-lg-4 col-md-4 col-sm-4 mb-3 mb-lg-0 pb-4\">\n                <div class=\"card card--white center-button-flexible\">\n                    <div class=\"thumbitem_overlay_4388\"><img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-299.jpg\" class=\"card-img-top \" alt=\"img\"><\/div>\n                    <div class=\"card-body thumbitemDesc \">\n                      <div><div class=\"card-title body-medium\"><h7>Cursos de verano<\/h7>\n<p>Nuestros cursos est\u00e1n abiertos a todos los ni\u00f1os, ya sean alumnos de ELIS Villamart\u00edn o no, y est\u00e1n dise\u00f1ados para fomentar la creatividad y las habilidades art\u00edsticas.<\/p><\/div><\/div><div class=\"component link text-center  btnBottom-flexible\"><a href=\"\/es\/escuela-de-verano\/\" class=\" btn btn-primary btn-primary--border\">Escuela de Verano<\/a><\/div><\/div>\n                <\/div>\n            <\/div><\/div>\n    <\/div>\n<\/section>[\/vc_column][\/vc_row][vc_row][vc_column]\n            <div class=\"wrapper\">\n    <section  id=\"english-access-course\"  style='' class=\"section    container-width  no-padding-list  \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component mb-1 mt-0  radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Curso intensivo de ingl\u00e9s nuestros alumnos<\/h2><\/div>\n                        <div class=\"sub-heading component \">\n                        <p class=\"body-medium\">Durante tres meses, nuestros alumnos, siguen un curso intensivo de un trimestre dise\u00f1ado para que refuercen sus conocimientos y comprensi\u00f3n del idioma y desarrollen las habilidades necesarias para acceder al resto del curr\u00edculo.<\/p>\n                        <\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"><div class=\"component single-img \"><div class=\"ratio ratio-16x9 callout-img halfcol--img image_overlay_1664\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-182.jpg);\"><\/div><\/div> <\/div>\n             <\/div>\n        <\/div>\n<\/section>\n            <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<section  id=\"facilities\"  class=\"section   section--blue   gradient1\" style=''>\n                        <div class=\"container-fluid pt-0\">       <div class=\"row m-0 align-items-center centerText\">\n                                <div class=\"col-sm-12 col-md-12 col-lg-10 mx-auto\">               <div class=\"sub-heading component\">\n                                        <h4 class=\"h4\">Un viaje de crecimiento y preparaci\u00f3n en ELIS Villamart\u00edn\n                                        <\/h4>\n                                    <\/div>            <\/div>\n                            <\/div><div class=\"row m-0 mt-5\">\n                                <div class=\"col-md-11 col-lg-11 col-xl-12 mx-auto  p-0 px-md-3\">\n                                    <div class=\"component slick-carousel\">\n                                        <div class=\"component slick-carousel\">\n                                            <div class=\"slick-slider--with-icon slick-slider full--slider\"><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-061.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-257.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-178.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-214.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-184.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-183.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-198.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-200.jpg');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n    \n                    <\/section>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694702386168{margin-top: 5px !important;background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/book-a-visit-banner-v3.png?id=69324) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;gradient2&#8243;][vc_column]<section  style='' class=\"section   section--blue   \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\"><div class=\"h2 \">Reserva una visita privada<\/div>\n<p>&nbsp;<\/p>\n<p>Descubre lo que una educaci\u00f3n en ELIS Villamart\u00edn tiene que ofrecer<\/p>\n<\/div><div class=\"component link\"><a href=\"\/es\/solicita-una-visita-privada\/\" class=\" btn btn-primary\">Reserve ahora<\/a><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section>[\/vc_column][\/vc_row][vc_row][vc_column]\n            <div class=\"wrapper\">\n    <section  style='' class=\"section    container-width pb-0   \" ><div class=\"container-fluid\"><div class=\"row    \"><div class=\" col-lg-6 col-md-6      \" ><div class=\"component   radius-bottom-LR \" style='px'><div class=\"sub-heading component\"><h2  class=\"h5  \">Preguntas Frecuentes<\/h2><\/div><\/div><\/div>\n                    <div class=\"col-lg-6 col-md-6    \"> <\/div>\n             <\/div>\n        <\/div>\n<\/section>\n            <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]\n            <div class=\"wrapper\"><section  class=\"section  container-width   \" style=''>\n                <div class=\"container-fluid\">\n                    <div class=\"row m-0\">\n                        <div class=\"col-md-12\">\n                            <div class=\"component\">\n                                <div class=\"accordion\" id=\"accordion\"><div class=\"accordion-item\">\n                                  <div class=\"h2 accordion-header\" id=\"heading1\">\n                                    <button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse1\" aria-expanded=\"false\" aria-controls=\"collapse1\">\n                                      \u00bfHay alg\u00fan tipo de apoyo psicol\u00f3gico o servicios de orientaci\u00f3n a los alumnos en ELIS Villamart\u00edn?\n                                    <\/button>\n                                  <\/div>\n                                  <div id=\"collapse1\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading1\" data-bs-parent=\"#accordion\">\n                                    <div class=\"accordion-body\"><div class=\" component\" style=\"margin-top:px\">\n                                        <div class=\"h6\">S\u00ed, el colegio ofrece apoyo psicol\u00f3gico y orientaci\u00f3n vocacional para ayudar a los estudiantes en su desarrollo personal y acad\u00e9mico.<\/div>\n                                    <\/div><\/div>\n                                <\/div>\n                            <\/div><div class=\"accordion-item\">\n                                  <div class=\"h2 accordion-header\" id=\"heading2\">\n                                    <button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse2\" aria-expanded=\"false\" aria-controls=\"collapse2\">\n                                      \u00bfC\u00f3mo se estructura la educaci\u00f3n secundaria en nuestro colegio de Alicante?\n                                    <\/button>\n                                  <\/div>\n                                  <div id=\"collapse2\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading2\" data-bs-parent=\"#accordion\">\n                                    <div class=\"accordion-body\"><div class=\" component\" style=\"margin-top:px\">\n                                        <div class=\"h6\">Sigue el Curr\u00edculo Nacional de Inglaterra y Gales, combinando sus asignaturas, con las adecuadas del sistema educativo espa\u00f1ol.<\/div>\n                                    <\/div><\/div>\n                                <\/div>\n                            <\/div><div class=\"accordion-item\">\n                                  <div class=\"h2 accordion-header\" id=\"heading3\">\n                                    <button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse3\" aria-expanded=\"false\" aria-controls=\"collapse3\">\n                                      \u00bfC\u00f3mo se prepara a los alumnos para los ex\u00e1menes IGCSE?\n                                    <\/button>\n                                  <\/div>\n                                  <div id=\"collapse3\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading3\" data-bs-parent=\"#accordion\">\n                                    <div class=\"accordion-body\"><div class=\" component\" style=\"margin-top:px\">\n                                        <div class=\"h6\">Durante la educaci\u00f3n secundaria, formamos a los alumnos con un curr\u00edculum especializado y apoyo adicional en los casos en los que as\u00ed lo requiera, para garantizar la adquisici\u00f3n de competencias necesarias para el \u00e9xito en sus  IGCSE de todos nuestros alumnos.<\/div>\n                                    <\/div><\/div>\n                                <\/div>\n                            <\/div><div class=\"accordion-item\">\n                                  <div class=\"h2 accordion-header\" id=\"heading4\">\n                                    <button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse4\" aria-expanded=\"false\" aria-controls=\"collapse4\">\n                                      \u00bfExiste apoyo acad\u00e9mico adicional?\n                                    <\/button>\n                                  <\/div>\n                                  <div id=\"collapse4\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading4\" data-bs-parent=\"#accordion\">\n                                    <div class=\"accordion-body\"><div class=\" component\" style=\"margin-top:px\">\n                                        <div class=\"h6\">S\u00ed, se ofrece refuerzo acad\u00e9mico personalizado a los estudiantes que lo necesiten.<\/div>\n                                    <\/div><\/div>\n                                <\/div>\n                            <\/div><\/div>\n                           <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/section>\n            <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"wrapper \" ><section  id=\"your-childs-journey\"  class=\"section container-width   section--blue \" style='background-color:#3c5128;margin-top:80px;'>\n    <div class=\"container-fluid \">\n        <div class=\"row m-0 centerText\">\n            \n<div class=\"col-sm-12 col-md-12 col-lg-10 col-xl-8 mx-auto\">       <div class=\"component\">\n                    <h3 class=\"h5\"><\/p>\n<h3>Inicia una experiencia de aprendizaje \u00fanica<\/h3>\n<p>\n                    <\/h3>\n                <\/div>     <\/div><div class=\"col-sm-12 col-md-7 col-lg-6 col-xl-5 mx-auto\">       <div class=\"component mt-3\">\n                    <div class=\"body-large\"><\/p>\n<p style=\"text-align: center\">Descubre el enriquecedor viaje educativo que espera a tu hijo en las diferentes etapas de El Limonar International School Villamart\u00edn.<\/p>\n<p><\/div>\n                <\/div>        <div class=\"component link\"><div class=\"component link\"><a href=\"\/es\/viaje-educativo-del-alumno\/\" class=\" btn btn-primary\">El viaje de tu hijo<\/a><\/div><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><section class=\"section cards--section pt-0 container-width  section--blue \" style='background-color:#3c5128;margin-bottom:80px;'>\n                <div class=\"container-fluid \">\n                    <div class=\"row m-0\"><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_9918\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-001.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal4411\">\n                                           <a href=\"\" class=\"body-large-bold\">Infantil<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">3 - 5 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal4411\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_8215\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-270.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal8983\">\n                                           <a href=\"\" class=\"body-large-bold\">Primaria<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">5 - 11 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal8983\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_7048\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-179.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal7962\">\n                                           <a href=\"\" class=\"body-large-bold\">Secundaria<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">11 - 16 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal7962\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div><div class=\"col-sm-12 col-md-6 col-lg-6\">\n                            <div class=\"card horizontal--card horizontal--card-sm img--100 mb-3\">\n                                <div class=\"row m-0 g-0\">                         <div class=\"col-5 col-md-5 col-lg-5\">\n                                    <div class=\"thumbnail_img_overlay_8329\"> <img decoding=\"async\" src=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-169.jpg\" class=\"img-fluid rounded-start\" alt=\"...\"><\/div>\n                                  <\/div>                        <div class=\"col-7 col-md-7 col-lg-7\">\n                                    <div class=\"card-body\">\n                                        <div class=\"component\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal2953\">\n                                           <a href=\"\" class=\"body-large-bold\">Bachillerato<\/a>\n                                        <\/div>\n                                        <div class=\"component m-0\"><p class=\"p\">16 - 18 a\u00f1os<\/p><\/div>                              <div class=\"modal-overlay sm--modal link\" data-bs-toggle=\"modal\" data-bs-target=\"#classmodal2953\">\n                                            <button class=\"btn btn-link\" title=\"Student journey popup link\"><i class=\"fa fa-plus\"><\/i><\/button>\n                                        <\/div>                           <\/div>\n                                  <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>          <\/div>\n                <\/div>\n            <\/section><\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal4411\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/infantil\/\" class=\"highlights__link btn btn-link\">Infantil<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">3 - 5 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Descubre nuestro curr\u00edculo dise\u00f1ado para ni\u00f1os de 3 a 5 a\u00f1os, que ofrece la base ideal para su itinerario educativo. <\/li>                       <li>Nuestras instalaciones proporcionan un ambiente acogedor, con personal altamente cualificado que garantiza una transici\u00f3n fluida desde la guarder\u00eda al colegio y un aprendizaje integral en siete \u00e1reas esenciales. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/infantil\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite9930 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-001.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal8983\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/primaria\/\" class=\"highlights__link btn btn-link\">Primaria<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">5 - 11 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Una educaci\u00f3n hol\u00edstica que prepara a los ni\u00f1os de 5 a 11 a\u00f1os para un crecimiento y aprendizaje continuos a lo largo de su vida. <\/li>                       <li>Nuestro curr\u00edculo combina lo mejor de la educaci\u00f3n brit\u00e1nica y espa\u00f1ola, ofreciendo un tercer idioma y un programa de tutor\u00eda individualizada. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/primaria\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite3433 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-270.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal7962\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/secundaria\/\" class=\"highlights__link btn btn-link\">Secundaria<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">11 - 16 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>Nuestro curr\u00edculo de Secundaria prepara a los estudiantes para ex\u00e1menes internacionales externos y rigurosos mejorando sus habilidades en diferentes materias. <\/li>                       <li>Nuestro compromiso con la excelencia se ve reflejado en nuestras instalaciones de primer nivel, que mejoran el aprendizaje y potencian la preparaci\u00f3n de los alumnos para el futuro. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/secundaria\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite5811 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-179.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div><div class=\"modal fade booking-modal extra--padding mob-P-0 show\" id=\"classmodal2953\" data-bs-backdrop=\"static\" data-bs-keyboard=\"false\" tabindex=\"-1\" aria-labelledby=\"staticBackdropLabel\" style=\"display: none;\" aria-modal=\"true\" role=\"dialog\">\n                                    <div class=\"modal-dialog modal-lg\">\n                                    <div class=\"modal-content section--white\">\n                                        <div class=\"modal-body\">\n                                            <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><i class=\"fa fa-times\"><\/i><\/button>\n                                            <div class=\"row m-0\">\n                                                <div class=\"col-md-6 col-lg-6 order-2 order-md-1 px-3 px-md-0 pt-4 pt-md-0\">\n                                                    <div class=\"col-md-12 col-lg-12\">\n                                                        <div class=\"component link\"><a href=\"\/es\/bachillerato\/\" class=\"highlights__link btn btn-link\">Bachillerato<\/a>                  <\/div>\n                                                        <div class=\"sub-heading component mt-0\">                <p class=\"body-small\">16 - 18 a\u00f1os<\/p>               <\/div>\n                                                    <\/div>           <div class=\"component list p-0\">\n                                                        <ul class=\"\">                       <li>ELIS Villamart\u00edn prepara a los estudiantes para acceder a universidades del Reino Unido, Espa\u00f1a o internacionales mediante un programa \u00fanico de orientaci\u00f3n vocacional. <\/li>                       <li>Nuestro Bachillerato combina A-Levels Internacionales y Bachillerato espa\u00f1ol, junto con un apoyo personalizado que incluye tutor\u00edas, intercambios, viajes y programas de preparaci\u00f3n para la universidad. <\/li>        <\/ul>\n                                                    <\/div>\n                                                    <div class=\"component link pt-3\">           <a class=\"btn btn-primary btn-primary--border\" href=\"\/es\/bachillerato\/\">Descubre m\u00e1s<\/a>           <\/div>\n                                                <\/div>\n                                                <div class=\"col-md-6 col-lg-6 order-1 order-md-2 p-0 p-md-3\">\n                                                    <div class=\"img-sec\">\n                                                        <div class=\"component\">\n                                                            <div class=\"modal_image_ite6196 callout-img map--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-169.jpg);background-position:center;\">\n                                                            <\/div>\n                                                            <\/div>\n                                                        <\/div>\n                                                        \n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n\n                                            \n                                        <\/div>\n                                    <\/div>\n                                    <\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<section  style='background-color:#f3f4f2;' class=\"section  light-color section--white pb-0  \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\">\n                                        <h2 class=\"h5\">Te puede interesar<\/h2>\n                                    <\/div><div class=\"sub-heading component\"><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section><section  class=\"section    pt-0  section--blue\" style='background-color:#f3f4f2;'><div class=\"container-fluid section--blue\" style='background-color:#f3f4f2'><style>\n            .background-box .heading .h5:after {\n                display:none;\n            }\n            <\/style><div class=\"row m-0 justify-content-center pt-3 pt-md-3\"><style>\n                .thumbnail_img_overlay_6106 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_6106 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_6106 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_6106 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_6106 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_6106 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_6106 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_6106\">   <a class=\"\" href = \"\/es\/excelencia-academica\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-182.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Excelencia Acad\u00e9mica<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_8553 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_8553 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_8553 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_8553 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_8553 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_8553 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_8553 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_8553\">   <a class=\"\" href = \"\/es\/instalaciones-y-localizacion\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-299.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Instalaciones y Localizaci\u00f3n<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_9558 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_9558 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_9558 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_9558 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_9558 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_9558 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_9558 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_9558\">   <a class=\"\" href = \"\/es\/proceso-de-admision\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-165.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Proceso de Admisi\u00f3n<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><style>\n                .thumbnail_img_overlay_5128 .callout-img.halfcol--img .img-overlay {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                .thumbnail_img_overlay_5128 .tech-images .callout-img.halfcol--img {\n                    background: rgba(0,0,0,0.5);\n                    \n                }\n\n                <\/style><style>\n                .thumbnail_img_overlay_5128 .heading .h5 {\n                    background: rgba(106,157,65,0.5);\n                    \n                }\n\n            \n\n                <\/style><style>\n                .thumbnail_img_overlay_5128 .heading .h5 a {\n                    font-size: 25px;\n                    line-height:25px;\n                    \n                }\n\n                .thumbnail_img_overlay_5128 .heading .h5 {\n                    font-size: 25px;\n                    line-height: 25px;\n                    \n                }\n               \n                <\/style><style>\n                .thumbnail_img_overlay_5128 .heading .h5 a {\n                    color: #ffffffpx;\n                    \n                }\n\n                .thumbnail_img_overlay_5128 .heading .h5 {\n                    color: #ffffffpx;\n                    \n                }\n               \n                <\/style><div class=\"col-lg-3 col-md-3 col-sm-3 mb-3 pb-2\">\n                            <div class=\"card card--white tech-images next-steps-module  thumbnail_img_overlay_5128\">   <a class=\"\" href = \"\/es\/puertas-abiertas-y-visitas\/\" ><div class=\"ratio ratio-21x9 callout-img halfcol--img leftBottom-content\" style=\"background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-047.jpg);background-position:center;\">\n                                 \n                                 <div class=\"img-overlay \">\n                                 \n                                     <div class=\"heading component\">\n                                        <h5 class=\"h5\" >Puertas Abiertas y Visitas<\/h5>\n                                     <\/div>\n                                   \n                                \n                             <\/div>\n                                 \n                                 <\/div><\/a>\n                            <\/div>\n                        <\/div><\/div><\/div>\n            <\/section>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694166801591{background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/prospectus-leaf.png?id=69327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]<section  style='' class=\"section   section--white   \"><div class=\"container-fluid\"><div class=\"row m-0 align-items-center centerText \" >\n                        <div class=\"col-sm-12 col-md-10 col-lg-9 mx-auto\"><div class=\"sub-heading component\">\n                                        <h2 class=\"h5\">Descubre m\u00e1s sobre ELIS Villamart\u00edn<\/h2>\n                                    <\/div><div class=\"sub-heading component\"><\/div><div class=\"component link\"><a href=\"\/es\/descarga-nuestro-catalogo\/\" class=\" btn btn-primary\">Solicita nuestro Cat\u00e1logo<\/a><\/div><style>\n                        .flex-button {\n                        margin-top: 25px;\n                    } \n                        \n                    @media (max-width: 767px){\n                     .flex-button {\n                      display: block;\n                      margin-left: 0;\n                    }\n                    .flex-button .text-center{\n                     text-align: left !important;\n                    }\n                    }\n\n\n                        <\/style><\/div><\/div><\/section>[\/vc_column][\/vc_row][vc_row][vc_column]<section class=\"section section--blue bottom-step TopBottomBorder   \" style=\"background-image: url('https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/08\/ELIS-Villarmartin-301.jpg');;background-position-y:75%;;\"><style>.bottom-step.section--blue:before {background: rgba(106,157,65,0.8);}<\/style><div class=\"container-fluid\"><div class=\"row\"><div class=\"col-sm-12\"><div class=\"component title\"><p class=\"body-small\">Ponte en Contacto<\/p><\/div><\/div><\/div><div class=\"row\"><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/haz-una-consulta\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Haz una Consulta<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/solicita-una-visita-privada\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Solicita una visita privada<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><div class=\"col-md-4\"><div class=\"component linkcard \">\n                                <a class=\"card card--bordered\" href=\"\/es\/reservar-una-jornada-de-puertas-abiertas\/\">\n                                    <div class=\"card-body d-flex align-items-center\">\n                                    <div> <div class=\"component link\">\n                                            <div  class=\"btn btn-link simple-link h5\">Ven a un D\u00eda de Puertas Abiertas<\/div>\n                                        <\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/section>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row el_class=&#8221;gradient1&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694702386168{margin-top: 5px !important;background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/book-a-visit-banner-v3.png?id=69324) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;gradient2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1694166801591{background-image: url(https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2023\/09\/prospectus-leaf.png?id=69327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":390,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-68977","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Instituto Secundaria en Alicante - Educaci\u00f3n Brit\u00e1nica<\/title>\n<meta name=\"description\" content=\"Nuestro Instituto de Secundaria en Alicante, ELIS Villamart\u00edn, sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas de secundaria impartidas en ingl\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elisvillamartin.com\/es\/secundaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instituto Secundaria en Alicante - Educaci\u00f3n Brit\u00e1nica\" \/>\n<meta property=\"og:description\" content=\"Nuestro Instituto de Secundaria en Alicante, ELIS Villamart\u00edn, sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas de secundaria impartidas en ingl\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elisvillamartin.com\/es\/secundaria\/\" \/>\n<meta property=\"og:site_name\" content=\"El Limonar International School Villamart\u00edn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T13:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instituto Secundaria en Alicante - Educaci\u00f3n Brit\u00e1nica","description":"Nuestro Instituto de Secundaria en Alicante, ELIS Villamart\u00edn, sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas de secundaria impartidas en ingl\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elisvillamartin.com\/es\/secundaria\/","og_locale":"es_ES","og_type":"article","og_title":"Instituto Secundaria en Alicante - Educaci\u00f3n Brit\u00e1nica","og_description":"Nuestro Instituto de Secundaria en Alicante, ELIS Villamart\u00edn, sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas de secundaria impartidas en ingl\u00e9s.","og_url":"https:\/\/elisvillamartin.com\/es\/secundaria\/","og_site_name":"El Limonar International School Villamart\u00edn","article_publisher":"https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/","article_modified_time":"2025-12-12T13:35:49+00:00","og_image":[{"width":1240,"height":575,"url":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elisvillamartin.com\/es\/secundaria\/","url":"https:\/\/elisvillamartin.com\/es\/secundaria\/","name":"Instituto Secundaria en Alicante - Educaci\u00f3n Brit\u00e1nica","isPartOf":{"@id":"https:\/\/elisvillamartin.com\/es\/#website"},"datePublished":"2021-09-22T09:41:27+00:00","dateModified":"2025-12-12T13:35:49+00:00","description":"Nuestro Instituto de Secundaria en Alicante, ELIS Villamart\u00edn, sigue el Curr\u00edculo Nacional de Inglaterra y Gales para las asignaturas de secundaria impartidas en ingl\u00e9s.","breadcrumb":{"@id":"https:\/\/elisvillamartin.com\/es\/secundaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elisvillamartin.com\/es\/secundaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elisvillamartin.com\/es\/secundaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elisvillamartin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Secundaria"}]},{"@type":"WebSite","@id":"https:\/\/elisvillamartin.com\/es\/#website","url":"https:\/\/elisvillamartin.com\/es\/","name":"El Limonar International School Villamart\u00edn","description":"ELIS Villamart\u00edn is part of the Cognita Schools Group","publisher":{"@id":"https:\/\/elisvillamartin.com\/es\/#organization"},"alternateName":"ELIS Villamartin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elisvillamartin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elisvillamartin.com\/es\/#organization","name":"ELIS Villamart\u00edn","alternateName":"ELIS Villamart\u00edn","url":"https:\/\/elisvillamartin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elisvillamartin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","contentUrl":"https:\/\/elisvillamartin.com\/wp-content\/uploads\/sites\/109\/2024\/11\/LOGO-ELIS-VILLAMARTIN-COLOR.jpg","width":1240,"height":575,"caption":"ELIS Villamart\u00edn"},"image":{"@id":"https:\/\/elisvillamartin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElLimonarInternationalSchoolVillamartin\/","https:\/\/www.instagram.com\/elis.villamartin"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/users\/390"}],"replies":[{"embeddable":true,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/comments?post=68977"}],"version-history":[{"count":32,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68977\/revisions"}],"predecessor-version":[{"id":73866,"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/pages\/68977\/revisions\/73866"}],"wp:attachment":[{"href":"https:\/\/elisvillamartin.com\/es\/wp-json\/wp\/v2\/media?parent=68977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}